{"id":137,"date":"2022-06-24T17:25:11","date_gmt":"2022-06-24T15:25:11","guid":{"rendered":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/?page_id=137"},"modified":"2022-06-24T17:25:11","modified_gmt":"2022-06-24T15:25:11","slug":"chad-danse","status":"publish","type":"page","link":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/chad-danse\/","title":{"rendered":"CHAD Danse"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-137","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/pages\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":1,"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/pages\/137\/revisions"}],"predecessor-version":[{"id":140,"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/pages\/137\/revisions\/140"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/enseignements-artistiques\/wp-json\/wp\/v2\/media?parent=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}