{"id":1216,"date":"2019-03-17T10:48:58","date_gmt":"2019-03-17T09:48:58","guid":{"rendered":"http:\/\/jane.ac\/?p=1216"},"modified":"2024-05-02T22:46:50","modified_gmt":"2024-05-02T20:46:50","slug":"benjamin-laroche-editeur","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/benjamin-laroche-editeur\/","title":{"rendered":"Benjamin LAROCHE, Jocatop"},"content":{"rendered":"<div id=\"pl-1216\"  class=\"panel-layout\" >\n<div id=\"pg-1216-0\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-1216-0-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-1216-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{&quot;class&quot;:&quot;blue-block&quot;,&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"blue-block panel-widget-style panel-widget-style-for-1216-0-0-0\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p style=\"text-align: center;\">Jane 2019 salon des \u00e9diteurs mars 2019 &#8211; Vandoeuvre les Nancy Facult\u00e9 de sciences et de technologie<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-1511 aligncenter\" src=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/BenjaminLaroche_Jocatop.jpg\" alt=\"\" width=\"94\" height=\"94\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/BenjaminLaroche_Jocatop.jpg 200w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/BenjaminLaroche_Jocatop-150x150.jpg 150w\" sizes=\"(max-width: 94px) 100vw, 94px\" \/>Benjamin Laroche, directeur commercial des \u00e9ditions JOCATOP souhaite rencontrer des repr\u00e9sentants et acteurs de l&rsquo;\u00e9ducation nationale de l&rsquo;\u00e9cole maternelle \u00e0 l&rsquo;\u00e9l\u00e9mentaire.<\/p>\n<p style=\"text-align: center;\"><iframe style=\"margin: 0; padding: 0; border: none;\" src=\"https:\/\/audioblog.arteradio.com\/embed\/134548\" width=\"480px\" height=\"122px\"><\/iframe><\/p>\n<p>De la maternelle au cycle 3, les Editions JOCATOP propose, des outils vari\u00e9s et innovants dans tous les domaines d\u2019activit\u00e9 : Langage, Graphisme, D\u00e9couverte du monde, Fran\u00e7ais, Math\u00e9matiques, Questionner le Monde, Histoire, G\u00e9ographie, Education Morale et Civique, Langues Vivantes, Pratiques Artistiques.<\/p>\n<p>La collection pr\u00e9sente des ensembles p\u00e9dagogiques avec toutes les ressources n\u00e9cessaires pour les \u00e9l\u00e8ves et l\u2019enseignant, classeurs d\u2019arts plastiques, jeux, logiciels, le\u00e7ons num\u00e9riques, applications tablettes.<\/p>\n<p>Pionnier dans le domaine du num\u00e9rique, JOCATOP con\u00e7oit aujourd\u2019hui des outils innovants pour les tableaux num\u00e9riques, ordinateurs et tablettes tactiles.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jane 2019 salon des \u00e9diteurs mars 2019 &#8211; Vandoeuvre les Nancy Facult\u00e9 de sciences et de technologie Benjamin Laroche, directeur commercial des \u00e9ditions JOCATOP souhaite rencontrer des repr\u00e9sentants et acteurs de l&rsquo;\u00e9ducation nationale de l&rsquo;\u00e9cole maternelle \u00e0 l&rsquo;\u00e9l\u00e9mentaire. De la maternelle au cycle 3, les Editions JOCATOP propose, des outils vari\u00e9s et innovants dans tous &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/benjamin-laroche-editeur\/\"> <span class=\"screen-reader-text\">Benjamin LAROCHE, Jocatop<\/span> Lire la suite\u00a0\u00bb<\/a><\/p>\n","protected":false},"author":4,"featured_media":1556,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/microphone.jpg",1920,1280,false],"thumbnail":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/microphone-150x150.jpg",150,150,true],"medium":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/microphone-300x200.jpg",300,200,true],"medium_large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/microphone-768x512.jpg",768,512,true],"large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/microphone-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/microphone.jpg",1536,1024,false],"2048x2048":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/microphone.jpg",1920,1280,false]},"uagb_author_info":{"display_name":"Herv\u00e9 Kowalczyk","author_link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/author\/hkowalczyk\/"},"uagb_comment_info":64,"uagb_excerpt":"Jane 2019 salon des \u00e9diteurs mars 2019 &#8211; Vandoeuvre les Nancy Facult\u00e9 de sciences et de technologie Benjamin Laroche, directeur commercial des \u00e9ditions JOCATOP souhaite rencontrer des repr\u00e9sentants et acteurs de l&rsquo;\u00e9ducation nationale de l&rsquo;\u00e9cole maternelle \u00e0 l&rsquo;\u00e9l\u00e9mentaire. De la maternelle au cycle 3, les Editions JOCATOP propose, des outils vari\u00e9s et innovants dans tous\u2026","_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1216"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/comments?post=1216"}],"version-history":[{"count":14,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1216\/revisions"}],"predecessor-version":[{"id":2280,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1216\/revisions\/2280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media\/1556"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media?parent=1216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/categories?post=1216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/tags?post=1216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}