{"id":1360,"date":"2019-03-15T16:19:39","date_gmt":"2019-03-15T15:19:39","guid":{"rendered":"http:\/\/jane.ac\/?p=1360"},"modified":"2024-05-02T22:46:50","modified_gmt":"2024-05-02T20:46:50","slug":"ressources-pour-linclusion-des-eleves-allophones","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/ressources-pour-linclusion-des-eleves-allophones\/","title":{"rendered":"Ressources pour l\u2019inclusion des \u00e9l\u00e8ves allophones"},"content":{"rendered":"<div id=\"pl-1360\"  class=\"panel-layout\" >\n<div id=\"pg-1360-0\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-1360-0-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-1360-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<h3 class=\"widget-title\">Ressources num\u00e9riques multimodales au service de l\u2019inclusion des \u00e9l\u00e8ves allophones<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p><strong>Mmes Claire Hornung, professeure-documentaliste, et Catherine Aubry, formatrice Casnav 1<sup>er<\/sup> degr\u00e9 (Casnav-Carep de Nancy-Metz)\u00a0: \u00ab\u00a0Ressources num\u00e9riques multimodales au service de l\u2019inclusion des \u00e9l\u00e8ves allophones\u00a0\u00bb<\/strong><strong><br \/>\n<\/strong><\/p>\n<p>Comment int\u00e9grer \u00e0 la classe un \u00e9l\u00e8ve nouvellement arriv\u00e9, non locuteur en langue fran\u00e7aise et parfois non lecteur\u00a0? Les ressources num\u00e9riques pr\u00e9sentent l\u2019immense avantage de mettre en correspondance diff\u00e9rentes modalit\u00e9s de perception sensorielle et s\u00e9miotique favorisant la compr\u00e9hension \u2013 production langagi\u00e8re. Quelques outils seront pr\u00e9sent\u00e9s qui apparaissent comme autant de ressources au service de l\u2019inclusion scolaire et sociale des \u00e9l\u00e8ves allophones.<\/p>\n<p style=\"text-align: center;\"><iframe src=\"https:\/\/fr.padlet.com\/claire_hornung1\/ghuvfyfvqcjy\" name=\"Mur virtuel Padlet\" width=\"1024\" height=\"768\"><\/iframe><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/fr.padlet.com\/claire_hornung1\/ghuvfyfvqcjy\" target=\"_blank\" rel=\"noopener noreferrer\">Consulter le mur virtuel en ligne<\/a><\/p>\n<p>Approfondir le sujet sur la site de la DANE : <a href=\"https:\/\/dane.ac-nancy-metz.fr\/numerique-ecole-inclusive\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/dane.ac-nancy-metz.fr\/numerique-ecole-inclusive\/<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ressources num\u00e9riques multimodales au service de l\u2019inclusion des \u00e9l\u00e8ves allophones Mmes Claire Hornung, professeure-documentaliste, et Catherine Aubry, formatrice Casnav 1er degr\u00e9 (Casnav-Carep de Nancy-Metz)\u00a0: \u00ab\u00a0Ressources num\u00e9riques multimodales au service de l\u2019inclusion des \u00e9l\u00e8ves allophones\u00a0\u00bb Comment int\u00e9grer \u00e0 la classe un \u00e9l\u00e8ve nouvellement arriv\u00e9, non locuteur en langue fran\u00e7aise et parfois non lecteur\u00a0? Les ressources num\u00e9riques &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/ressources-pour-linclusion-des-eleves-allophones\/\"> <span class=\"screen-reader-text\">Ressources pour l\u2019inclusion des \u00e9l\u00e8ves allophones<\/span> Lire la suite\u00a0\u00bb<\/a><\/p>\n","protected":false},"author":5,"featured_media":1274,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/Seminaire-inclusion-atelier-12.jpg",960,640,false],"thumbnail":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/Seminaire-inclusion-atelier-12-150x150.jpg",150,150,true],"medium":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/Seminaire-inclusion-atelier-12-300x200.jpg",300,200,true],"medium_large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/Seminaire-inclusion-atelier-12-768x512.jpg",768,512,true],"large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/Seminaire-inclusion-atelier-12.jpg",960,640,false],"1536x1536":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/Seminaire-inclusion-atelier-12.jpg",960,640,false],"2048x2048":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/Seminaire-inclusion-atelier-12.jpg",960,640,false]},"uagb_author_info":{"display_name":"Kadriye Cikmazkara","author_link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/author\/kcikmazkara\/"},"uagb_comment_info":59,"uagb_excerpt":"Ressources num\u00e9riques multimodales au service de l\u2019inclusion des \u00e9l\u00e8ves allophones Mmes Claire Hornung, professeure-documentaliste, et Catherine Aubry, formatrice Casnav 1er degr\u00e9 (Casnav-Carep de Nancy-Metz)\u00a0: \u00ab\u00a0Ressources num\u00e9riques multimodales au service de l\u2019inclusion des \u00e9l\u00e8ves allophones\u00a0\u00bb Comment int\u00e9grer \u00e0 la classe un \u00e9l\u00e8ve nouvellement arriv\u00e9, non locuteur en langue fran\u00e7aise et parfois non lecteur\u00a0? Les ressources num\u00e9riques\u2026","_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1360"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/comments?post=1360"}],"version-history":[{"count":6,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1360\/revisions"}],"predecessor-version":[{"id":3721,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1360\/revisions\/3721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media\/1274"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media?parent=1360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/categories?post=1360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/tags?post=1360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}