{"id":1417,"date":"2019-03-22T18:46:20","date_gmt":"2019-03-22T17:46:20","guid":{"rendered":"http:\/\/jane.ac\/?p=1417"},"modified":"2024-05-02T22:46:49","modified_gmt":"2024-05-02T20:46:49","slug":"d-col","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/d-col\/","title":{"rendered":"D-Col"},"content":{"rendered":"<div id=\"pl-1417\"  class=\"panel-layout\" >\n<div id=\"pg-1417-0\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-1417-0-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-1417-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{&quot;class&quot;:&quot;blue-block&quot;,&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"blue-block panel-widget-style panel-widget-style-for-1417-0-0-0\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>Pr\u00e9sentation du dispositif D\u2019Col par Milena Delette et Virginie Ventana\u00a0 du Cned sur le pavillon acad\u00e9mique\u00a0 accompagn\u00e9es par deux enseignantes Val\u00e9rie Pereaux\u00a0 et Val\u00e9rie Weber r\u00e9f\u00e9rentes du dispositif devoirs faits . D\u2019COL est un dispositif num\u00e9rique d\u2019aide aux \u00e9l\u00e8ves de sixi\u00e8me en difficult\u00e9, en fran\u00e7ais, en math\u00e9matiques et en anglais.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone  wp-image-1418 aligncenter\" src=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-300x161.jpg\" alt=\"\" width=\"175\" height=\"94\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-300x161.jpg 300w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-768x412.jpg 768w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-1024x549.jpg 1024w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison.jpg 1920w\" sizes=\"(max-width: 175px) 100vw, 175px\" \/><\/p>\n<p style=\"text-align: center;\">Lien internet\u00a0: <a href=\"https:\/\/www.dcol.fr\/\">https:\/\/www.dcol.fr\/<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sentation du dispositif D\u2019Col par Milena Delette et Virginie Ventana\u00a0 du Cned sur le pavillon acad\u00e9mique\u00a0 accompagn\u00e9es par deux enseignantes Val\u00e9rie Pereaux\u00a0 et Val\u00e9rie Weber r\u00e9f\u00e9rentes du dispositif devoirs faits . D\u2019COL est un dispositif num\u00e9rique d\u2019aide aux \u00e9l\u00e8ves de sixi\u00e8me en difficult\u00e9, en fran\u00e7ais, en math\u00e9matiques et en anglais. Lien internet\u00a0: https:\/\/www.dcol.fr\/<\/p>\n","protected":false},"author":1,"featured_media":1418,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison.jpg",1920,1029,false],"thumbnail":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-150x150.jpg",150,150,true],"medium":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-300x161.jpg",300,161,true],"medium_large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-768x412.jpg",768,412,true],"large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison-1024x549.jpg",1024,549,true],"1536x1536":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison.jpg",1536,823,false],"2048x2048":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/ecolemaison.jpg",1920,1029,false]},"uagb_author_info":{"display_name":"hleclerc","author_link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/author\/hleclerc\/"},"uagb_comment_info":64,"uagb_excerpt":"Pr\u00e9sentation du dispositif D\u2019Col par Milena Delette et Virginie Ventana\u00a0 du Cned sur le pavillon acad\u00e9mique\u00a0 accompagn\u00e9es par deux enseignantes Val\u00e9rie Pereaux\u00a0 et Val\u00e9rie Weber r\u00e9f\u00e9rentes du dispositif devoirs faits . D\u2019COL est un dispositif num\u00e9rique d\u2019aide aux \u00e9l\u00e8ves de sixi\u00e8me en difficult\u00e9, en fran\u00e7ais, en math\u00e9matiques et en anglais. Lien internet\u00a0: https:\/\/www.dcol.fr\/","_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1417"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/comments?post=1417"}],"version-history":[{"count":1,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1417\/revisions"}],"predecessor-version":[{"id":1419,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/1417\/revisions\/1419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media\/1418"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media?parent=1417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/categories?post=1417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/tags?post=1417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}