{"id":2769,"date":"2020-01-27T10:11:18","date_gmt":"2020-01-27T09:11:18","guid":{"rendered":"http:\/\/jane.ac\/?p=2769"},"modified":"2024-05-02T22:46:47","modified_gmt":"2024-05-02T20:46:47","slug":"lenvironnement-numerique-de-travail","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/lenvironnement-numerique-de-travail\/","title":{"rendered":"L\u2019environnement num\u00e9rique de travail"},"content":{"rendered":"<div id=\"pl-2769\"  class=\"panel-layout\" >\n<div id=\"pg-2769-0\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-2769-0-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-2769-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{&quot;class&quot;:&quot;blue-block&quot;,&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"blue-block panel-widget-style panel-widget-style-for-2769-0-0-0\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<h4>Vendredi 27 mars<\/h4>\n<h5>Parcours 4 : Vie scolaire et num\u00e9rique<\/h5>\n<p>L\u2019environnement num\u00e9rique de travail<\/p>\n<ul>\n<li>le d\u00e9veloppement et l\u2019usage de nouvelles pratiques p\u00e9dagogiques en particulier dans les liaisons \u00e9cole\/coll\u00e8ge ou maternelle\/\u00e9l\u00e9mentaire<\/li>\n<li>l\u2019ouverture de l\u2019\u00e9cole aux parents, renforcer la relation \u00e9cole-famille<\/li>\n<li>l\u2019int\u00e9gration dans un projet d\u2019individualisation du parcours de chaque l\u2019\u00e9l\u00e8ve<\/li>\n<li>le d\u00e9veloppement de nouvelles formes de travail entre les enseignants\u00a0: cr\u00e9er un espace de mutualisation, collaboratif, contributif et interactif<\/li>\n<\/ul>\n<table style=\"border-collapse: collapse; width: 100%;\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 18.2527693856999%;\"><img loading=\"lazy\" class=\"alignnone  wp-image-2629 aligncenter\" src=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/IMG_1015-1-292x300.jpg\" alt=\"\" width=\"129\" height=\"133\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/IMG_1015-1-292x300.jpg 292w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/IMG_1015-1-768x788.jpg 768w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/IMG_1015-1-998x1024.jpg 998w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/IMG_1015-1.jpg 1400w\" sizes=\"(max-width: 129px) 100vw, 129px\" \/><\/td>\n<td style=\"width: 15.936555891238669%;\"><img loading=\"lazy\" class=\"alignnone  wp-image-2630 aligncenter\" src=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/pascalburgain-300x300.jpg\" alt=\"\" width=\"136\" height=\"136\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/pascalburgain-300x300.jpg 300w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/pascalburgain-150x150.jpg 150w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/pascalburgain-510x510.jpg 510w, https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/pascalburgain.jpg 512w\" sizes=\"(max-width: 136px) 100vw, 136px\" \/><\/td>\n<td style=\"width: 65.81067472306142%;\"><strong>Sophie ROLEE, <\/strong><em>chef de projet ENT \u00e0 la DANE de Nancy<\/em><\/p>\n<p><strong>Pascal BURGAIN, <\/strong><em>Conseiller p\u00e9dagogique d\u00e9partemental charg\u00e9 du num\u00e9rique, DSDEN54<\/em><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vendredi 27 mars Parcours 4 : Vie scolaire et num\u00e9rique L\u2019environnement num\u00e9rique de travail le d\u00e9veloppement et l\u2019usage de nouvelles pratiques p\u00e9dagogiques en particulier dans les liaisons \u00e9cole\/coll\u00e8ge ou maternelle\/\u00e9l\u00e9mentaire l\u2019ouverture de l\u2019\u00e9cole aux parents, renforcer la relation \u00e9cole-famille l\u2019int\u00e9gration dans un projet d\u2019individualisation du parcours de chaque l\u2019\u00e9l\u00e8ve le d\u00e9veloppement de nouvelles formes de &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sites.ac-nancy-metz.fr\/jane\/lenvironnement-numerique-de-travail\/\"> <span class=\"screen-reader-text\">L\u2019environnement num\u00e9rique de travail<\/span> Lire la suite\u00a0\u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":2770,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"uagb_featured_image_src":{"full":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/environnementnumerique.jpg",1920,777,false],"thumbnail":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/environnementnumerique-150x150.jpg",150,150,true],"medium":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/environnementnumerique-300x121.jpg",300,121,true],"medium_large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/environnementnumerique-768x311.jpg",768,311,true],"large":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/environnementnumerique-1024x414.jpg",1024,414,true],"1536x1536":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/environnementnumerique.jpg",1536,622,false],"2048x2048":["https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-content\/uploads\/environnementnumerique.jpg",1920,777,false]},"uagb_author_info":{"display_name":"hleclerc","author_link":"https:\/\/sites.ac-nancy-metz.fr\/jane\/author\/hleclerc\/"},"uagb_comment_info":65,"uagb_excerpt":"Vendredi 27 mars Parcours 4 : Vie scolaire et num\u00e9rique L\u2019environnement num\u00e9rique de travail le d\u00e9veloppement et l\u2019usage de nouvelles pratiques p\u00e9dagogiques en particulier dans les liaisons \u00e9cole\/coll\u00e8ge ou maternelle\/\u00e9l\u00e9mentaire l\u2019ouverture de l\u2019\u00e9cole aux parents, renforcer la relation \u00e9cole-famille l\u2019int\u00e9gration dans un projet d\u2019individualisation du parcours de chaque l\u2019\u00e9l\u00e8ve le d\u00e9veloppement de nouvelles formes de\u2026","_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/2769"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/comments?post=2769"}],"version-history":[{"count":2,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/2769\/revisions"}],"predecessor-version":[{"id":2772,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/posts\/2769\/revisions\/2772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media\/2770"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/media?parent=2769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/categories?post=2769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/jane\/wp-json\/wp\/v2\/tags?post=2769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}