{"id":1403,"date":"2019-03-17T21:54:12","date_gmt":"2019-03-17T20:54:12","guid":{"rendered":"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/?p=1403"},"modified":"2026-05-13T08:53:00","modified_gmt":"2026-05-13T06:53:00","slug":"journaliste-dun-jour","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/journaliste-dun-jour\/","title":{"rendered":"Journaliste d&#8217;un jour"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>Les \u00e9l\u00e8ves de premi\u00e8re ES du lyc\u00e9e Alfred M\u00e9zi\u00e8res , apprentis journalistes d&#8217;un jour au centre mondial de la Paix \u00e0 Verdun.<\/strong><\/p>\n\n\n\n<p>Mercredi 19 Septembre 2018, la classe de premi\u00e8re ES3 s\u2019est\nrendue \u00e0 Verdun, au Centre Mondial de la Paix, accompagn\u00e9e par deux professeurs\nde Fran\u00e7ais et d\u2019Histoire-G\u00e9ographie, Mme Dubas et M. Fonte, pour rencontrer\nles organisateurs du projet Journaliste d\u2019un Jour et les autres lyc\u00e9es\nparticipants.<\/p>\n\n\n\n<p>Deux expositions \u00e9taient propos\u00e9es aux \u00e9l\u00e8ves, qui r\u00e9partis\nen deux groupes ont pu travailler, soit sur la Grande Guerre, soit sur les\ncadeaux offerts aux diff\u00e9rents Pr\u00e9sidents de la r\u00e9publique au fil des ann\u00e9es.\nAinsi, l\u2019\u00e9volution des sciences, de la communication, de la propagande, des\narmes, la place des civils et notamment des femmes durant la guerre ont \u00e9t\u00e9 des\nsujets d\u2019articles possibles pour ces journalistes en herbe.<\/p>\n\n\n\n<p>L\u2019apr\u00e8s-midi a \u00e9t\u00e9 consacr\u00e9e \u00e0 des rencontres avec diff\u00e9rents professionnels attach\u00e9s au devoir m\u00e9moire, fil conducteur des deux expositions propos\u00e9es au Centre Mondial de la Paix.<\/p>\n\n\n\n<p>Retrouvez sur le site du R\u00e9publicain Lorrain, toutes les<strong> <\/strong><a rel=\"noreferrer noopener\" aria-label=\"photos  (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.republicain-lorrain.fr\/actualite\/2018\/09\/24\/photos-journaliste-d-un-jour-grand-est-2018-revivez-la-deuxieme-journee-au-centre-mondial-de-la-paix-avec-les-lycees-de-lorraine-et-de-champagne-ardenne#0_16 \" target=\"_blank\"><strong>photos<\/strong> <\/a>de cet \u00e9v\u00e9nement.<\/p>\n\n\n\n<p>Bertrand BAUD, directeur du <em><a rel=\"noreferrer noopener\" aria-label=\"R\u00e9publicain lorrain (s\u2019ouvre dans un nouvel onglet)\" href=\"https:\/\/www.republicain-lorrain.fr\/edition-de-longwy\" target=\"_blank\">R\u00e9publicain lorrain<\/a><\/em> de Longwy, est venu guider les \u00e9l\u00e8ves dans leur travail de r\u00e9daction. Les articles r\u00e9dig\u00e9s par les \u00e9l\u00e8ves sont parus dans une \u00e9dition sp\u00e9ciale du <em>R\u00e9publicain lorrain<\/em>, sur cinq jours, entre le 8 et le 13 octobre 2018. <\/p>\n\n\n\n<p>Une belle exp\u00e9rience pour nos jeunes journalistes, passeurs\nde m\u00e9moire&nbsp;! <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9l\u00e8ves de premi\u00e8re ES du lyc\u00e9e Alfred M\u00e9zi\u00e8res , apprentis journalistes d&#8217;un jour au centre mondial de la Paix<\/p>\n","protected":false},"author":1,"featured_media":1405,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[43,10],"tags":[48],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1403"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/comments?post=1403"}],"version-history":[{"count":2,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1403\/revisions"}],"predecessor-version":[{"id":4882,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1403\/revisions\/4882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media\/1405"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media?parent=1403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/categories?post=1403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/tags?post=1403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}