{"id":1498,"date":"2019-03-31T09:57:39","date_gmt":"2019-03-31T07:57:39","guid":{"rendered":"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/?p=1498"},"modified":"2026-05-13T08:54:23","modified_gmt":"2026-05-13T06:54:23","slug":"porsche-et-la-gastronomie-allemande-nont-plus-de-secret-pour-eux","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/porsche-et-la-gastronomie-allemande-nont-plus-de-secret-pour-eux\/","title":{"rendered":"Porsche et la gastronomie allemande n\u2019ont plus de secret pour eux"},"content":{"rendered":"\n<p class=\"has-text-color has-vivid-green-cyan-color\">Accompagn\u00e9s par leurs professeurs M. Sujkowski, A. Pinelli et B. Geant,  cinquante \u00e9l\u00e8ves de 1\u00e8re se sont rendus \u00e0 Stuttgart. <strong> <\/strong><\/p>\n\n\n\n<p>Les visites guid\u00e9es leur ont permis d\u2019en apprendre davantage sur l\u2019histoire de cette marque automobile de luxe, de sa cr\u00e9ation par Ferdinand Porsche en 1931 jusqu\u2019\u00e0 la \u00ab&nbsp;Mission E&nbsp;\u00bb, le concept de la voiture \u00e9lectrique prochainement commercialis\u00e9e par l\u2019entreprise.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/03\/museum-porsche1.jpg\" alt=\"\" class=\"wp-image-1502\" width=\"425\" height=\"319\"\/><figcaption>Vendredi 29 mars-Stuttgart-Capitale du Bade-Wurtemberg<\/figcaption><\/figure><\/div>\n\n\n\n<p>Place ensuite, sous le soleil, \u00e0 la d\u00e9couverte de la ville \u00e0 travers un \u00ab&nbsp;rallye-photo&nbsp;\u00bb qui a amen\u00e9 les \u00e9l\u00e8ves \u00e0 se rendre dans des endroits strat\u00e9giques et \u00e0 converser dans la langue de Goethe pour r\u00e9aliser les missions qui leur \u00e9taient confi\u00e9es. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/03\/museum-porsche2.jpg\" alt=\"\" class=\"wp-image-1503\" width=\"388\" height=\"291\"\/><figcaption>Mus\u00e9e Porsche<\/figcaption><\/figure><\/div>\n\n\n\n<p>Le groupe ne pouvait quitter la ville le ventre vide. Le restaurant souabe \u00ab&nbsp;Ochs\u2019n Willi&nbsp;\u00bb leur a donc pr\u00e9par\u00e9 un menu de sp\u00e9cialit\u00e9s locales&nbsp;: des \u00ab&nbsp;Maultaschen&nbsp;\u00bb (ravioles farcies), de l\u2019Apfelk\u00fcchle (pommes tremp\u00e9es dans de la p\u00e2te) et un verre d\u2019Apfelschorle (jus de pommes p\u00e9tillant). <\/p>\n\n\n\n<p>Tout le monde est rentr\u00e9 repu et ravi \u00e0 Longwy \u00e0 0h20. Une sortie qui augurait un agr\u00e9able week-end avant la reprise des cours.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accompagn\u00e9s par leurs professeurs M. Sujkowski, A. Pinelli et B. Geant, cinquante \u00e9l\u00e8ves de 1\u00e8re se sont rendus \u00e0 Stuttgart.<\/p>\n","protected":false},"author":1,"featured_media":1497,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[43,5],"tags":[42,34],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1498"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/comments?post=1498"}],"version-history":[{"count":1,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1498\/revisions"}],"predecessor-version":[{"id":4884,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1498\/revisions\/4884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media\/1497"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/categories?post=1498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/tags?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}