{"id":1788,"date":"2019-11-24T16:28:12","date_gmt":"2019-11-24T15:28:12","guid":{"rendered":"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/?p=1788"},"modified":"2026-05-13T12:38:46","modified_gmt":"2026-05-13T10:38:46","slug":"une-semaine-en-roumanie","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/une-semaine-en-roumanie\/","title":{"rendered":"Une semaine en Roumanie"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>Douze \u00e9l\u00e8ves de premi\u00e8re se sont rendus en Roumanie pour la 3<\/strong><sup><strong>\u00e8me<\/strong><\/sup><strong> \u00e9tape du projet-Erasmus+ \u00ab Gender in equality \u00bb.<\/strong><\/p>\n\n\n\n<p>Ce voyage du 6 au 12 octobre 2019 entrait dans le cadre du grand projet <em>Erasmus+<\/em> qui a \u00e9t\u00e9 mis en place par notre \u00e9tablissement et enti\u00e8rement financ\u00e9 par l\u2019Union Europ\u00e9enne. Ce projet qui s\u2019\u00e9tale sur deux ans, regroupe 4 lyc\u00e9es de 4 pays de l\u2019Union Europ\u00e9enne&nbsp;: Portugal, Roumanie, Lettonie et France, autour de la th\u00e9matique \u00ab&nbsp;<em><strong>r\u00e9duire les in\u00e9galit\u00e9s Femmes\/Hommes<\/strong>&nbsp;<\/em>\u00bb et o\u00f9 la langue commune utilis\u00e9e par les diff\u00e9rents partenaires est l\u2019Anglais. <\/p>\n\n\n\n<p>C\u2019est de Charleroi, en Belgique, que notre petit groupe s\u2019est\nenvol\u00e9, le dimanche 6 octobre, \u00e0 destination de Bucarest\u2026 et d\u00e9j\u00e0 un premier\nmoment fort pour deux de nos \u00e9l\u00e8ves, qui n\u2019avaient jamais pris l\u2019avion&nbsp;!<\/p>\n\n\n\n<p>A notre arriv\u00e9e, la pluie de Longwy a fait place au soleil et\nles correspondants roumains, qui nous attendaient \u00e0 l\u2019a\u00e9roport, nous avaient\nr\u00e9serv\u00e9 un chaleureux accueil. D\u00e8s lors, chacun a rejoint sa famille\n\u00ab&nbsp;d\u2019adoption&nbsp;\u00bb pour vivre pendant une semaine au rythme de la vie\nroumaine.<\/p>\n\n\n\n<p>Le lundi matin a \u00e9t\u00e9 le moment de la rencontre et des\npr\u00e9sentations entre tous ces jeunes issus des quatre coins de l\u2019Europe. <\/p>\n\n\n\n<p>Les \u00e9l\u00e8ves roumains nous ont ensuite fait d\u00e9couvrir leur pays\net leur ville, \u00e0 travers des vid\u00e9os, avant de nous faire visiter leur lyc\u00e9e et\nde nous apprendre quelques rudiments de leur langue sous forme de jeux.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"794\" height=\"1024\" src=\"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/photo-Roumanie-2-794x1024.jpg\" alt=\"\" class=\"wp-image-1786\" style=\"width:378px;height:488px\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/photo-Roumanie-2-794x1024.jpg 794w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/photo-Roumanie-2-233x300.jpg 233w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/photo-Roumanie-2-768x990.jpg 768w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/photo-Roumanie-2-560x722.jpg 560w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/photo-Roumanie-2.jpg 1434w\" sizes=\"(max-width: 794px) 100vw, 794px\" \/><\/figure><\/div>\n\n\n<p>L\u2019apr\u00e8s-midi a \u00e9t\u00e9 consacr\u00e9e \u00e0 la visite du th\u00e9\u00e2tre national,\nguid\u00e9e par un com\u00e9dien. Cette construction moderne, en plein centre de la\ncapitale, \u00e9tag\u00e9e sur sept niveaux, qui ne laisse pas indiff\u00e9rent, nous a\nd\u00e9voil\u00e9 tous ses secrets. <\/p>\n\n\n\n<p>Le mardi matin a \u00e9t\u00e9 r\u00e9serv\u00e9 \u00e0 l\u2019intervention de conf\u00e9renciers.\nD\u2019abord sur la place de la femme dans la litt\u00e9rature, et plus particuli\u00e8rement\nchez Hom\u00e8re, dans l\u2019Iliade et l\u2019Odyss\u00e9e. Cette pr\u00e9sentation a \u00e9t\u00e9 faite par un\nprofesseur d\u2019universit\u00e9, ayant fait ses \u00e9tudes en France, candidat aux futures\n\u00e9lections pr\u00e9sidentielles dans son pays. Ensuite, deux conf\u00e9renci\u00e8res,\n\u00e9galement professeures d\u2019universit\u00e9, pr\u00e9sent\u00e8rent les \u00e9l\u00e9ments d\u2019in\u00e9galit\u00e9s\nFemmes\/hommes dans le domaine du sport. <\/p>\n\n\n\n<p>L\u2019apr\u00e8s-midi, nous avons visit\u00e9 le Palais du Parlement (deuxi\u00e8me\nplus grand b\u00e2timent du monde apr\u00e8s le Pentagone), folie d\u2019un homme, Nicolae\nCeau\u0219escu qui, dans les ann\u00e9es 1980, n\u2019h\u00e9sita pas \u00e0 raser des hectares\nd\u2019habitations pour afficher sa grandeur.<\/p>\n\n\n\n<p>Le mercredi matin, les \u00e9l\u00e8ves, en groupes internationaux, ont\neu \u00e0 r\u00e9fl\u00e9chir sur les questions li\u00e9es aux in\u00e9galit\u00e9s femmes\/hommes dans le\nsport et la culture et ce, en vue d\u2019\u00e9tablir un questionnaire destin\u00e9 \u00e0\ninterroger, de retour dans leur pays, des personnes de leur entourage sur ces\ndeux th\u00e8mes.<\/p>\n\n\n\n<p>L\u2019apr\u00e8s-midi a \u00e9t\u00e9 consacr\u00e9e \u00e0 une visite de la vieille ville\nde Bucarest, entre \u00e9glises orthodoxes et autres b\u00e2timents de styles tr\u00e8s h\u00e9t\u00e9roclites&nbsp;:\nann\u00e9es 1920\/1930, p\u00e9riode communiste, moderne, etc.<\/p>\n\n\n\n<p>Toute la journ\u00e9e du jeudi s&#8217;est pass\u00e9e loin de la capitale,\nd\u2019abord \u00e0 Sina\u00efa, pour y visiter le ch\u00e2teau de Peles, construit \u00e0 la fin du\nXIX\u00e8me si\u00e8cle, et qui a \u00e9t\u00e9 la r\u00e9sidence d\u2019\u00e9t\u00e9 du 1<sup>er<\/sup> roi de\nRoumanie, Carol 1<sup>er<\/sup>. Ensuite en Transylvanie, \u00e0 Bran, pour y\nd\u00e9couvrir son ch\u00e2teau connu sous le nom de ch\u00e2teau de Dracula&nbsp;! Il a en\neffet \u00e9t\u00e9 la demeure du prince Vlad Tepes, que la l\u00e9gende a d\u00e9crit comme sanguinaire\nparce qu&#8217;il empalait ses contradicteurs et qui buvait leur sang. Derni\u00e8re \u00e9tape\ndu jour&nbsp;: la jolie ville de Brasov, 3<sup>\u00e8me<\/sup> plus grande ville du\npays.<\/p>\n\n\n\n<p>Vendredi matin, au lyc\u00e9e, toujours en groupes internationaux,\nles \u00e9l\u00e8ves ont \u00e9t\u00e9 amen\u00e9s \u00e0 r\u00e9fl\u00e9chir \u00e0 des propositions qu\u2019ils auraient \u00e0\nfaire aux d\u00e9put\u00e9s europ\u00e9ens pour r\u00e9duire les in\u00e9galit\u00e9s femmes\/hommes dans l\u2019UE,\nen mati\u00e8re de sport et de culture. De tr\u00e8s bonnes id\u00e9es ont \u00e9t\u00e9 avanc\u00e9es que\nnous irons d\u00e9poser au Parlement de Bruxelles, en mars 2020.<\/p>\n\n\n\n<p>La fin de matin\u00e9e a \u00e9t\u00e9 consacr\u00e9e \u00e0 l\u2019apprentissage de danses\ntraditionnelles, sous la f\u00e9rule de deux professeurs d\u2019EPS. <\/p>\n\n\n\n<p>Dans l\u2019apr\u00e8s-midi, retour en ville pour les derniers achats\nde souvenirs et autres.<\/p>\n\n\n\n<p>Le s\u00e9jour s\u2019est conclu le vendredi soir au lyc\u00e9e o\u00f9 tous les\n\u00e9l\u00e8ves, les professeurs, les parents ont pu d\u00e9guster diff\u00e9rents mets locaux\npr\u00e9par\u00e9s par les familles. Nos h\u00f4tes nous ont ensuite offert des cadeaux\nsouvenirs avant que nous nous disions un dernier au revoir.<\/p>\n\n\n\n<p>Samedi, r\u00e9veil \u00e0 03h30 du matin pour reprendre l\u2019avion \u00e0 9 h.\nLe soleil, qui ne nous avait pas quitt\u00e9s de la semaine, \u00e9tait de retour avec\nnous \u00e0 Longwy. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Douze \u00e9l\u00e8ves de premi\u00e8re se sont rendus en Roumanie pour la 3\u00e8me \u00e9tape du projet-Erasmus+ \u00ab Gender in equality \u00bb.<\/p>\n","protected":false},"author":1,"featured_media":1787,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[43,4,50],"tags":[17,49,34],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1788"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/comments?post=1788"}],"version-history":[{"count":1,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1788\/revisions"}],"predecessor-version":[{"id":4901,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1788\/revisions\/4901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media\/1787"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media?parent=1788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/categories?post=1788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/tags?post=1788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}