{"id":1800,"date":"2019-11-24T16:44:17","date_gmt":"2019-11-24T15:44:17","guid":{"rendered":"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/?p=1800"},"modified":"2026-05-13T12:39:11","modified_gmt":"2026-05-13T10:39:11","slug":"travailler-en-anglais-avec-des-partenaires-espagnols","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/travailler-en-anglais-avec-des-partenaires-espagnols\/","title":{"rendered":"Travailler en anglais&#8230; avec des partenaires espagnols"},"content":{"rendered":"\n<p class=\"has-text-color has-vivid-green-cyan-color\"><strong>Le projet- eTwinning &#8211; a mis en relation  une classe de premi\u00e8re de notre lyc\u00e9e avec des \u00e9l\u00e8ves en Espagne. <\/strong><\/p>\n\n\n\n<p> Ils ont travaill\u00e9 toute l\u2019ann\u00e9e de mani\u00e8re virtuelle autour du projet eTwinning intitul\u00e9 \u00ab <em><strong>My heroes, your heroes, our heroes<\/strong><\/em> \u00bb tout en communiquant en anglais. <\/p>\n\n\n\n<p>L&#8217;objectif \u00e9tait de leur permettre de r\u00e9fl\u00e9chir\nau concept de h\u00e9ros, tout en encourageant la pratique de l&#8217;anglais, l\u2019usage\nd\u2019outils num\u00e9riques et la collaboration pour la cr\u00e9ation de plusieurs\nproductions communes (jeux interactifs, ebook sur les h\u00e9ros de tous les temps).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"466\" height=\"463\" src=\"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/My-heroes-logo.png\" alt=\"\" class=\"wp-image-1803\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/My-heroes-logo.png 466w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/My-heroes-logo-150x150.png 150w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2019\/11\/My-heroes-logo-300x298.png 300w\" sizes=\"(max-width: 466px) 100vw, 466px\" \/><\/figure><\/div>\n\n\n\n<p>Leur travail est disponible\nici : <a href=\"https:\/\/twinspace.etwinning.net\/71864\/home\">https:\/\/twinspace.etwinning.net\/71864\/home<\/a> <\/p>\n\n\n\n<p>Ce projet a re\u00e7u le label de qualit\u00e9 europ\u00e9en.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le projet- eTwinning &#8211; a mis en relation une classe de premi\u00e8re de notre lyc\u00e9e avec des \u00e9l\u00e8ves en Espagne.<\/p>\n","protected":false},"author":1,"featured_media":1802,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[43,4,16],"tags":[17,18],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1800"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/comments?post=1800"}],"version-history":[{"count":1,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1800\/revisions"}],"predecessor-version":[{"id":4902,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/1800\/revisions\/4902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media\/1802"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media?parent=1800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/categories?post=1800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/tags?post=1800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}