{"id":3369,"date":"2023-07-06T17:20:40","date_gmt":"2023-07-06T15:20:40","guid":{"rendered":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/?p=3369"},"modified":"2024-01-18T15:54:30","modified_gmt":"2024-01-18T14:54:30","slug":"les-eleves-de-loption-theatre-en-sortie-scolaire","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/les-eleves-de-loption-theatre-en-sortie-scolaire\/","title":{"rendered":"Les \u00e9l\u00e8ves de l\u2019option th\u00e9\u00e2tre en sortie scolaire"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-color has-text-color\"><strong>Le d\u00e9part a eu lieu en fin de matin\u00e9e le 2 juin \u00e0 la gare de Thionville, direction Paris !<\/strong><\/p>\n\n\n\n<p>Apr\u00e8s une exp\u00e9rience dans le RER, la troupe est arriv\u00e9e \u00e0 l\u2019Ecole de formation de l\u2019acteur Auvray Nauroy. Elle a \u00e9t\u00e9 accueillie par Eram Shobani ,co-directeur , accompagn\u00e9 par Paul Tilmont, com\u00e9dien.<\/p>\n\n\n\n<p>La d\u00e9couverte du lieu a \u00e9t\u00e9 une surprise pour les lyc\u00e9ens habitu\u00e9s \u00e0 un cadre scolaire classique, ici pas de salle de cours mais des salles &nbsp;repr\u00e9sentations \u00e9quip\u00e9es de syst\u00e8me son et lumi\u00e8res, des salles de r\u00e9p\u00e9tition. Ils ont aussi pu d\u00e9couvrir une biblioth\u00e8que m\u00e9diath\u00e8que dans un cadre intimiste .<\/p>\n\n\n\n<p>Le d\u00e9jeuner a eu lieu \u00e0 la salle Edith Piaf, o\u00f9 tous \u00e9taient r\u00e9unis autour d\u2019une grande table au foyer des \u00e9l\u00e8ves. Les \u00e9l\u00e8ves de l\u2019option ont \u00e9t\u00e9 invit\u00e9s \u00e0 la premi\u00e8re pr\u00e9sentation de maquette d&#8217;Ubu Roi.<\/p>\n\n\n\n<p>Eram Shobani qui l\u2019a mise en sc\u00e8ne, a tenu \u00e0 pr\u00e9senter lui-m\u00eame la pi\u00e8ce Ubu roi, insistant \u00e0 la fois sur son caract\u00e8re absurde mais aussi sur l\u2019\u00e9criture singuli\u00e8re d\u2019Alfred Jarry. M\u00e8re Ubu va pousser son mari \u00e0 d\u00e9tr\u00f4ner le roi ce qui va entrainer une soif de pouvoir incontr\u00f4lable chez P\u00e8re Ubu. Devenant un roi sanguinaire, autoritaire et sans piti\u00e9 qui sombre peu \u00e0 peu dans la folie&#8230;<\/p>\n\n\n\n<p>Mise en sc\u00e8ne Eram Sobhani interpr\u00e9tation Natalie Beder, Thomas Nolet, Paul Tilmont, Bastien Touminet cr\u00e9ation lumi\u00e8re et r\u00e9gie g\u00e9n\u00e9rale Arnault Philippe.<\/p>\n\n\n\n<p>Les \u00e9l\u00e8ves ont \u00e9t\u00e9 m\u00e9dus\u00e9s face \u00e0 un d\u00e9cor impressionnant. La sc\u00e9nographe Nathalie Savary a su cr\u00e9er un d\u00e9cor original en instaurant une ambiance morbide alliant le noir et blanc sur une toile de fond cauchemardesque.Sur sc\u00e8ne, le fantastique domine avec un squelette de cheval, un ours blanc et un char qui se d\u00e9place alors que les roues ne touchent pas le sol.<\/p>\n\n\n\n<p>Le com\u00e9dien Paul Tilmont, incarnant Ubu, a parfaitement jou\u00e9 la mont\u00e9e vers la folie du personnage gr\u00e2ce \u00e0 un jeu impressionnant. Les lyc\u00e9ens ont pu remarquer \u00e0 quel point la personne qui les a accueillis et celle qui \u00e9tait sur sc\u00e8ne \u00e9tait incroyablement diff\u00e9rente.<\/p>\n\n\n\n<p>L\u2019omnipr\u00e9sence de la mort \u00e0 travers les massacres perp\u00e9tu\u00e9s par ce roi sanguinaire a \u00e9t\u00e9 habilement mise en sc\u00e8ne par le biais d\u2019un th\u00e9\u00e2tre de marionettes&nbsp; : des cr\u00e2nes en papier mach\u00e9 symboliquement jet\u00e9s afin de retranscrire l\u2019horreur des actes commis par Ubu.<\/p>\n\n\n\n<p>La tension dramatique \u00e9tait maintenue \u00e9galement \u00e0 travers l\u2019intervention de batterie, chant et instrument \u00e0 cordes.<\/p>\n\n\n\n<p>&nbsp;Cette pr\u00e9sentation a suscit\u00e9 des r\u00e9actions diff\u00e9rentes : elle a d\u00e9clench\u00e9 le rire chez certains qui ont \u00e9t\u00e9 sensibles \u00e0 la mont\u00e9e en puissance absurde de ce pouvoir, elle a emport\u00e9 d\u2019autres dans le monde fantastique et morbide, mais tous ont \u00e9t\u00e9 r\u00e9ellement impressionn\u00e9s par la performance des com\u00e9diens, le d\u00e9cor et la mise en sc\u00e8ne.<\/p>\n\n\n\n<p>A l&#8217;issue de la pr\u00e9sentation, un temps d&#8217;\u00e9change entre les \u00e9l\u00e8ves et le metteur en sc\u00e8ne Eram Shobani s\u2019est av\u00e9r\u00e9 tr\u00e8s enrichissant.<\/p>\n\n\n\n<p>Le metteur en sc\u00e8ne a pu recueillir les impressions diverses, r\u00e9pondre aux questions li\u00e9es \u00e0 la mise en sc\u00e8ne, comprendre le choix de la pi\u00e8ce et d\u00e9couvrir le processus de travail en amont.<\/p>\n\n\n\n<p>Ce qu\u2019il faut retenir c\u2019est que ce choix r\u00e9pond th\u00e9\u00e2tralement \u00e0 l&#8217;horreur politique pr\u00e9sente dans l\u2019actualit\u00e9 de certains pays. Une farce du pouvoir qui fait entendre le cri des victimes. La machinerie de la mise en sc\u00e8ne est en lambeaux \u00e0 l\u2019image du monde en lambeaux.<\/p>\n\n\n\n<p>Pour finir, les lyc\u00e9ens ont pratiqu\u00e9 un \u00e9chauffement avec Eram Shobani qui enseigne \u00e9galement dans cette \u00e9cole de formation de l\u2019acteur. Un travail sur l\u2019espace, la voix, l\u2019articulation et l\u2019improvisation, permettant ainsi de conforter certains dans leur choix d\u2019orientation professionnelle d\u2019\u00e9tudes th\u00e9\u00e2trales.<\/p>\n\n\n\n<p>Merci \u00e0 l\u2019\u00e9quipe de l\u2019\u00e9cole pour son accueil, la qualit\u00e9 de la prestation, la richesse des \u00e9changes, l\u2019invitation \u00e0 la pr\u00e9sentation de maquette. Mme Richard<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9part a eu lieu en fin de matin\u00e9e le 2 juin \u00e0 la gare de Thionville, direction Paris !<\/p>\n","protected":false},"author":1,"featured_media":3371,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[43,12,11],"tags":[34,24],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/3369"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/comments?post=3369"}],"version-history":[{"count":0,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/3369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media\/3371"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media?parent=3369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/categories?post=3369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/tags?post=3369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}