{"id":3773,"date":"2024-06-28T16:27:58","date_gmt":"2024-06-28T14:27:58","guid":{"rendered":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/?p=3773"},"modified":"2024-09-17T08:25:35","modified_gmt":"2024-09-17T06:25:35","slug":"sarah-gurcel-vermande-traductrice","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/sarah-gurcel-vermande-traductrice\/","title":{"rendered":"Sarah Gurcel-Vermande, traductrice"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-5bdfab44da8900125e25762de42f4083\"><strong>Fin mars 2024, Sarah Gurcel Vermande est venue au lyc\u00e9e Alfred M\u00e9zi\u00e8res de Longwy pour animer des ateliers de traduction.<\/strong><\/p>\n\n\n\n<p>Actrice, bilingue anglais-fran\u00e7ais, elle traduit des pi\u00e8ces de th\u00e9\u00e2tre, comme <em>Never Vera Blue <\/em>d\u2019Alexandra Wood, mais aussi des romans. <\/p>\n\n\n\n<p>Apr\u00e8s une pr\u00e9sentation de son travail, elle propose aux \u00e9l\u00e8ves de travailler sur des extraits de textes o\u00f9 chacun pouvait discuter de la pertinence des propositions. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"838\" data-id=\"3769\" src=\"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction-2-1024x838.jpg\" alt=\"\" class=\"wp-image-3769\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction-2-1024x838.jpg 1024w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction-2-300x245.jpg 300w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction-2-768x628.jpg 768w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction-2-560x458.jpg 560w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction-2.jpg 1208w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"694\" data-id=\"3772\" src=\"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction1-1024x694.jpg\" alt=\"\" class=\"wp-image-3772\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction1-1024x694.jpg 1024w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction1-300x203.jpg 300w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction1-768x521.jpg 768w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction1-560x380.jpg 560w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2024\/06\/Atelier-de-traduction1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Les \u00e9l\u00e8ves de la sp\u00e9cialit\u00e9 &#8220;Anglais Monde Contemporain&#8221; (AMC) ou de &#8221; Langues, Litt\u00e9ratures et Cultures \u00c9trang\u00e8res&#8221; (LLCE) ont bien profit\u00e9 de cet atelier qui les pr\u00e9pare un peu plus \u00e0 l\u2019\u00e9preuve de traduction du baccalaur\u00e9at.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fin mars 2024, Sarah Gurcel Vermande est venue au lyc\u00e9e Alfred M\u00e9zi\u00e8res de Longwy pour animer des ateliers de traduction.<\/p>\n","protected":false},"author":1,"featured_media":3771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[43,4],"tags":[17],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/3773"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/comments?post=3773"}],"version-history":[{"count":0,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/3773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media\/3771"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media?parent=3773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/categories?post=3773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/tags?post=3773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}