{"id":4294,"date":"2025-11-14T08:51:58","date_gmt":"2025-11-14T07:51:58","guid":{"rendered":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/?p=4294"},"modified":"2025-12-21T15:32:08","modified_gmt":"2025-12-21T14:32:08","slug":"film-italien-de-villerupt","status":"publish","type":"post","link":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/film-italien-de-villerupt\/","title":{"rendered":"\u00a0Film Italien de Villerupt"},"content":{"rendered":"\n<p class=\"has-vivid-green-cyan-color has-text-color has-link-color wp-elements-8310e022f83235b28fe4fefc5b3385c6\"><strong>Les\u00a0lyc\u00e9ens de langue vivante Italien (sections Euro, Esabac, LV) se sont rendus au Festival du Film Italien de Villerupt<\/strong>. &#8211;<\/p>\n\n\n\n<p>Au programme du <a href=\"https:\/\/festival-villerupt.com\/\" data-type=\"link\" data-id=\"https:\/\/festival-villerupt.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">festival du film italien de Villerupt<\/a> et dans la nouvelle salle culturelle de l&#8217;Arche, deux films : &#8220;US Palmese&#8221; sur le monde du football, et &#8220;La Vita Da Grandi&#8221; sur le monde du handicap et de l&#8217;autisme. Tous deux ont rencontr\u00e9 succ\u00e8s et attention de la part de nos \u00e9l\u00e8ves, dont le comportement et le s\u00e9rieux ont \u00e9t\u00e9 salu\u00e9s par les b\u00e9n\u00e9voles de cette importante manifestation. <\/p>\n\n\n\n<p>De plus, comme chaque ann\u00e9e, une de nos \u00e9l\u00e8ves a eu l&#8217;honneur de faire partie du Jury Jeunes, Mlle Yousra Marrhoubi (Terminale Esabac). Ce fut pour elle une exp\u00e9rience incroyable, de rencontrer le monde du cin\u00e9ma italien \u00e0 Villerupt.\u00a0A noter que &#8220;La\u00a0Vita da Grandi&#8221; a re\u00e7u l&#8217;Amilcar du Jury.&#8221;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"http:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2025\/11\/FFIV-2025-AFFICHE.jpg\" alt=\"\" class=\"wp-image-4291\" style=\"width:490px;height:auto\" srcset=\"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2025\/11\/FFIV-2025-AFFICHE.jpg 595w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2025\/11\/FFIV-2025-AFFICHE-212x300.jpg 212w, https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-content\/uploads\/2025\/11\/FFIV-2025-AFFICHE-560x792.jpg 560w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Les\u00a0lyc\u00e9ens de langue vivante Italien (sections Euro, Esabac, LV) se sont rendus au Festival du Film Italien de Villerupt. &#8211;<\/p>\n","protected":false},"author":1,"featured_media":4293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[43,72,6],"tags":[32],"_links":{"self":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/4294"}],"collection":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/comments?post=4294"}],"version-history":[{"count":0,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/posts\/4294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media\/4293"}],"wp:attachment":[{"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/media?parent=4294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/categories?post=4294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.ac-nancy-metz.fr\/lyc-alfred-mezieres-longwy\/wp-json\/wp\/v2\/tags?post=4294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}